{"id":2346,"date":"2016-01-23T12:51:48","date_gmt":"2016-01-23T10:51:48","guid":{"rendered":"http:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png"},"modified":"2016-01-23T13:10:19","modified_gmt":"2016-01-23T11:10:19","slug":"razeebuss-radicall-v-4-5-2","status":"inherit","type":"attachment","link":"https:\/\/razeebuss.com\/en\/razeebuss-radicall-last-virtual-cage-flight-test\/razeebuss-radicall-v-4-5-2\/","title":{"rendered":"Razeebuss Radicall v.4 5"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-2346","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Razeebuss Radicall v.4 5 - RAZEEBUSS AIRCRAFT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/razeebuss.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Razeebuss Radicall : Last Virtual Cage flight test\",\"item\":\"https:\/\/razeebuss.com\/en\/razeebuss-radicall-last-virtual-cage-flight-test\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Razeebuss Radicall v.4 5\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Razeebuss Radicall v.4 5 - RAZEEBUSS AIRCRAFT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/razeebuss.com\/"},{"@type":"ListItem","position":2,"name":"Razeebuss Radicall : Last Virtual Cage flight test","item":"https:\/\/razeebuss.com\/en\/razeebuss-radicall-last-virtual-cage-flight-test\/"},{"@type":"ListItem","position":3,"name":"Razeebuss Radicall v.4 5"}]}]}},"jetpack_shortlink":"https:\/\/wp.me\/a4ScjR-BQ","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-300x225.png 300w, https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-768x576.png 768w, https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1024x768.png 1024w, https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x600.png 800w, https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png 1040w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-wp-pid=\"2346\" data-attachment-id=\"2346\" data-permalink=\"https:\/\/razeebuss.com\/en\/razeebuss-radicall-last-virtual-cage-flight-test\/razeebuss-radicall-v-4-5-2\/\" data-orig-file=\"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png\" data-orig-size=\"1040,780\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Razeebuss Radicall v.4 5\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-300x225.png\" data-large-file=\"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1024x768.png\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1040,"height":780,"file":"2016\/01\/Razeebuss-Radicall-v.4-5.png","sizes":{"thumbnail":{"file":"Razeebuss-Radicall-v.4-5-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-150x150.png"},"medium":{"file":"Razeebuss-Radicall-v.4-5-300x225.png","width":300,"height":225,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-300x225.png"},"medium_large":{"file":"Razeebuss-Radicall-v.4-5-768x576.png","width":768,"height":576,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-768x576.png"},"large":{"file":"Razeebuss-Radicall-v.4-5-1024x768.png","width":1024,"height":768,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1024x768.png"},"post-thumbnail":{"file":"Razeebuss-Radicall-v.4-5-672x372.png","width":672,"height":372,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-672x372.png"},"twentyfourteen-full-width":{"file":"Razeebuss-Radicall-v.4-5-1038x576.png","width":1038,"height":576,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1038x576.png"},"ngfb-tc-summary":{"file":"Razeebuss-Radicall-v.4-5-200x200.png","width":200,"height":200,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-200x200.png"},"ngfb-tc-lrgimg":{"file":"Razeebuss-Radicall-v.4-5-300x225.png","width":300,"height":225,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-300x225.png"},"ngfb-pinterest-button":{"file":"Razeebuss-Radicall-v.4-5-800x600.png","width":800,"height":600,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x600.png"},"ngfb-buffer-button":{"file":"Razeebuss-Radicall-v.4-5-800x780.png","width":800,"height":780,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x780.png"},"ngfb-tumblr-button":{"file":"Razeebuss-Radicall-v.4-5-800x600.png","width":800,"height":600,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x600.png"},"ngfb-schema":{"file":"Razeebuss-Radicall-v.4-5-800x600.png","width":800,"height":600,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x600.png"},"wpsso-schema":{"file":"Razeebuss-Radicall-v.4-5-800x600.png","width":800,"height":600,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-800x600.png"},"wpsso-tc-lrgimg":{"file":"Razeebuss-Radicall-v.4-5-1040x628-cropped.png","width":1040,"height":628,"filesize":0,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1040x628-cropped.png"},"wpsso-thumbnail":{"file":"Razeebuss-Radicall-v.4-5-1040x628-cropped.png","width":1040,"height":628,"filesize":0,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1040x628-cropped.png"},"wpsso-schema-16x9":{"file":"Razeebuss-Radicall-v.4-5-1040x675-cropped.png","width":1040,"height":675,"filesize":0,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1040x675-cropped.png"},"wpsso-opengraph":{"file":"Razeebuss-Radicall-v.4-5-1040x628-cropped.png","width":1040,"height":628,"filesize":0,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5-1040x628-cropped.png"},"full":{"file":"Razeebuss-Radicall-v.4-5.png","width":1040,"height":780,"mime_type":"image\/png","source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0,"keywords":[]}},"post":2358,"source_url":"https:\/\/razeebuss.com\/wp-content\/uploads\/2016\/01\/Razeebuss-Radicall-v.4-5.png","_links":{"self":[{"href":"https:\/\/razeebuss.com\/en\/wp-json\/wp\/v2\/media\/2346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/razeebuss.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/razeebuss.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/razeebuss.com\/en\/wp-json\/wp\/v2\/users\/1"}]}}